{"id":566,"date":"2020-06-13T00:00:00","date_gmt":"2020-06-13T00:00:00","guid":{"rendered":"https:\/\/www.theschooloflife.com\/berlin\/blog\/2020\/06\/13\/unser-recht-auf-schlechte-laune\/"},"modified":"2024-09-24T11:39:00","modified_gmt":"2024-09-24T11:39:00","slug":"unser-recht-auf-schlechte-laune","status":"publish","type":"post","link":"https:\/\/www.theschooloflife.com\/berlin\/blog\/unser-recht-auf-schlechte-laune\/","title":{"rendered":"Unser Recht auf schlechte Laune"},"content":{"rendered":"\n<p>Die offizielle Religion der Moderne ist das Gl\u00fccklichsein. Das kann auf den ersten Blick gut klingen, aber st\u00e4ndig heiter zu sein, ist eine extrem einschr\u00e4nkende Forderung. Es gibt eine Freiheit, die uns so auf subtile, aber schreckliche Weise vorenthalten wird: die Freiheit, ungl\u00fccklich zu sein.<\/p>\n\n\n\n<p>Der Kinderpsychoanalytiker Donald Winnicott entwickelte ein besonderes Misstrauen gegen\u00fcber solchen Menschen, die, wann immer sie ein Baby sehen, versuchen, es mit aller Kraft zum L\u00e4cheln zu bringen. Sie machen lustige Gesichter, spielen Kuckuck, wippen das Kind auf und ab, kitzeln seine Zehen &#8211; und h\u00f6ren nicht auf, bis das Baby endlich ein paar Lacher von sich gibt. Ein auf diese Weise fr\u00f6hlicher und aufgedrehter Mensch unterscheidet sich von einem gl\u00fccklichen Menschen; ein gl\u00fccklicher Mensch l\u00e4chelt, weil er Lust dazu hat, ein aufgedrehter Mensch l\u00e4chelt, weil er dazu gezwungen ist, weil in seinem Inneren allerlei unverarbeiteter Kummer steckt, vor dem er manisch auf der Flucht ist. Wenn solche Menschen f\u00fcr einen Moment aufh\u00f6ren w\u00fcrden zu lachen, m\u00fcssten sie vielleicht all das erkennen, dem sie sich bisher nicht stellen konnten; all die Emotionen, die sie nicht wahrzunehmen wagen, die Wut auf jemanden, der sie im Stich gelassen hat, die Wut auf etwas oder jemanden, den sie lieben sollten, die Schuldgef\u00fchle aufgrund eines schweren Fehlers, den sie begangen haben.<\/p>\n\n\n\n<p>Es ist unnat\u00fcrlich, wenn jemand l\u00e4nger als f\u00fcnfzehn Minuten am St\u00fcck unbeschwert und ohne Traurigkeit bleibt. Irgendetwas D\u00fcsteres zeichnet sich immer am Horizont ab. Deshalb ist die Vorstellung, nicht nur gelegentlich sehr gl\u00fccklich, sondern grunds\u00e4tzlich und dauerhaft fr\u00f6hlich zu sein, ein so beunruhigender Gedanke, der auf einer Verleugnung der Realit\u00e4t beruht. Selbst Babys haben viel, wor\u00fcber sie traurig sein k\u00f6nnen. Sie haben gerade erst den Mutterleib verlassen, den bequemsten, intuitivsten und n\u00e4hrendsten Ort auf Erden, und m\u00fcssen all die Entt\u00e4uschungen entdecken, die der Versuch, sich zu ern\u00e4hren und f\u00fcr sein eigenes Wohlergehen zu sorgen, mit sich bringt. Sie haben noch so viel zu lernen. Vielleicht erleben sie sogar schon die ersten Andeutungen von Sterblichkeit. Warum sollte eine so komplexe Kreatur dazu geneigt sein, mehr zu tun als nur gelegentlich ein Kichern loszulassen?<\/p>\n\n\n\n<hr style=\"width: 100%; height: 1px; background-color: #000; margin-bottom: 30px; margin-top: 20px\">\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">The School of Life<br><strong>Leading the AI-Transformation \u2013<\/strong> <strong>Gratis Workshop f\u00fcr HR <\/strong><\/h2>\n\n\n\n<p>KI ver\u00e4ndert Aufgaben, Rollen und Entscheidungsprozesse rasant. Unser Gratis-Workshop stellt HR-Professionals einen klaren Orientierungsrahmen vor, wie F\u00fchrungskr\u00e4fte im KI-Zeitalter agieren k\u00f6nnen, um Ver\u00e4nderung nicht zu blockieren, sondern tragf\u00e4hig zu gestalten.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"771\" src=\"https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2026\/02\/23094042\/260223-Leading-Transformation-AI-Kopie-1024x771.webp\" alt=\"\" class=\"wp-image-33361\" style=\"object-fit:cover\" srcset=\"https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2026\/02\/23094042\/260223-Leading-Transformation-AI-Kopie-1024x771.webp 1024w, https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2026\/02\/23094042\/260223-Leading-Transformation-AI-Kopie-300x226.webp 300w, https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2026\/02\/23094042\/260223-Leading-Transformation-AI-Kopie-768x578.webp 768w, https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2026\/02\/23094042\/260223-Leading-Transformation-AI-Kopie.webp 1440w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline\" style=\"text-align: center;\"><a style=\"font-size:19px;\" class=\"wp-block-button__link\" href=\"https:\/\/www.theschooloflife.com\/berlin\/events\/gratis-workshop-fur-hr-leading-change-im-ki-zeitalter\/\">Jetzt mehr erfahren<\/a><\/div>\n\n\n\n<hr style=\"width: 100%; height: 1px; background-color: #000; margin-top: 30px; margin-bottom: 20px\">\n\n\n\n<p class=\"has-text-align-center\"><strong>Die Gesellschaft will uns einfach nicht in Ruhe lassen<\/strong><\/p>\n\n\n\n<p>Leider ist die moderne Gesellschaft wie ein riesiger Spa\u00dfvogel. Sie will uns st\u00e4ndig hochnehmen und mit uns Kuckuck spielen. Medien, Werbung, Partys, Freunde &#8211; alle verschw\u00f6ren sich, um uns zu suggerieren, dass es irgendwie normal w\u00e4re, st\u00e4ndig Erfolge zu feiern und sich gespr\u00e4chig, ausgeglichen, optimistisch und leichtf\u00fc\u00dfig zu f\u00fchlen.<\/p>\n\n\n\n<p>Wir sollten anerkennen d\u00fcrfen, dass das Leben ein Hospiz ist und kein Krankenhaus, dass wir dem Untergang geweiht und kr\u00e4nkelnd sind, dass uns auf Schritt und Tritt die Angst folgt, dass wir ungeheuer zerbrechlich sind und immer an der Schwelle zu einer neuen entt\u00e4uschenden Erkenntnis stehen.<\/p>\n\n\n\n<p>Wir sollten niemals gezwungen sein, jemandem zu sagen, dass es uns &#8220;gut&#8221; geht. Die selbstverst\u00e4ndliche Vorannahme sollte sein, dass wir uns selbstverst\u00e4ndlich in irgendeiner Art von Krise befinden: finanziell, romantisch, in Bezug auf unseren Ruf, existentiell &#8211; denn so sind wir Menschen nun einmal. Wir sollten die Unterstellung von den Plakatw\u00e4nden ausmerzen, dass unser Leben jemals unbeschwert und sonnig werden k\u00f6nnte. Selbst im Urlaub werden wir nat\u00fcrlich ungl\u00fccklich sein. Auch wenn wir in einigen Aspekten unseres Lebens &#8220;gut&#8221; abgeschnitten haben, werden wir die meiste Zeit mit den Nerven am Ende sein. Nat\u00fcrlich hassen wir uns selbst und w\u00fcnschen uns, wir h\u00e4tten die meisten Dinge anders gemacht.<\/p>\n\n\n\n<p>Wir brauchen eine Gesellschaft, die uns in dem Zustand annimmt, in dem wir sind &#8211; nicht eine, die versucht, uns sinnlos aufzuheitern. Wir wissen in unseren Herzen, und wenn wir um 4 Uhr morgens in Panik aufwachen, wie es wirklich l\u00e4uft &#8211; wie anstrengend, ver\u00e4ngstigend, unruhig, \u00e4rgerlich und uneindeutig unser Leben ist. Die n\u00e4chste Stufe unserer Entwicklung wird darin bestehen, das, was wir \u00fcber uns selbst wissen, anzuerkennen und eine Gesellschaft um uns herum aufzubauen, die den Mut hat, ihre wahre psychologische Komplexit\u00e4t zu akzeptieren.<\/p>\n\n\n\n<p><em>Aus diesem Grund hat es sich The School of Life zur Aufgabe gemacht, einen Ort zu schaffen, an dem wir uns mit in ungesch\u00f6nter und aufrichtiger Form mit uns selbst und unserem Alltag auseinandersetzen k\u00f6nnen. So gelangen wir Schritt f\u00fcr Schritt zu mehr Selbsterkenntnis und zu einem besseren, anstelle eines fr\u00f6hlicheren Lebens.<\/em><\/p>\n\n\n\n<p><em><br><\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"353\" src=\"https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2025\/06\/08185910\/240312-Blog-School-Hinweis-Kopie-1024x353.webp\" alt=\"\" class=\"wp-image-31283\" srcset=\"https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2025\/06\/08185910\/240312-Blog-School-Hinweis-Kopie-1024x353.webp 1024w, https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2025\/06\/08185910\/240312-Blog-School-Hinweis-Kopie-300x103.webp 300w, https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2025\/06\/08185910\/240312-Blog-School-Hinweis-Kopie-768x265.webp 768w, https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2025\/06\/08185910\/240312-Blog-School-Hinweis-Kopie.jpg.webp 1102w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Wir unterst\u00fctzen dich bei deiner pers\u00f6nlichen und beruflichen Entwicklung und helfen Organisationen, die psychologisch-emotionalen F\u00e4higkeiten ihrer F\u00fchrungskr\u00e4fte und Teams zu st\u00e4rken.<\/p>\n\n\n\n<div class=\"wp-block-button is-style-outline\" style=\"text-align: center;\"><a style=\"font-size:22px;\" class=\"wp-block-button__link\" href=\"https:\/\/www.theschooloflife.com\/berlin\/?utm_source=Website&#038;utm_medium=Button&#038;utm_campaign=lp0100\">Lerne uns kennen<\/a><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1440\" height=\"1084\" src=\"https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2025\/01\/26091622\/250325-Spring-Retreat-Kopie-1.jpg\" alt=\"\" class=\"wp-image-30750\" style=\"object-fit:cover\" srcset=\"https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2025\/01\/26091622\/250325-Spring-Retreat-Kopie-1.jpg.webp 1440w, https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2025\/01\/26091622\/250325-Spring-Retreat-Kopie-1-300x226.jpg.webp 300w, https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2025\/01\/26091622\/250325-Spring-Retreat-Kopie-1-1024x771.jpg.webp 1024w, https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2025\/01\/26091622\/250325-Spring-Retreat-Kopie-1-768x578.jpg.webp 768w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\">Spring Retreat in Berlin \u2013 Klarheit, Fokus und Ver\u00e4nderung<\/p>\n\n\n\n<div class=\"wp-block-button is-style-outline\" style=\"text-align: center;\"><a style=\"font-size:15px;\" class=\"wp-block-button__link\" href=\"https:\/\/www.theschooloflife.com\/berlin\/events\/spring-retreat-klarheit-fokus-und-veranderung\/\">Mehr dazu<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1440\" height=\"1084\" src=\"https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2025\/02\/26091807\/250325-Abschied-vom-Berufsleben-Kopie-2.jpg\" alt=\"\" class=\"wp-image-30751\" style=\"object-fit:cover\" srcset=\"https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2025\/02\/26091807\/250325-Abschied-vom-Berufsleben-Kopie-2.jpg.webp 1440w, https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2025\/02\/26091807\/250325-Abschied-vom-Berufsleben-Kopie-2-300x226.jpg.webp 300w, https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2025\/02\/26091807\/250325-Abschied-vom-Berufsleben-Kopie-2-1024x771.jpg.webp 1024w, https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2025\/02\/26091807\/250325-Abschied-vom-Berufsleben-Kopie-2-768x578.jpg.webp 768w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\">Abschied vom Berufsleben Retreat in Berlin \u2013 Wie ich meinen neuen Lebensabschnitt erf\u00fcllend gestalte<\/p>\n\n\n\n<div class=\"wp-block-button is-style-outline\" style=\"text-align: center;\"><a style=\"font-size:15px;\" class=\"wp-block-button__link\" href=\"https:\/\/www.theschooloflife.com\/berlin\/events\/abschied-vom-berufsleben-retreat-wie-ich-meinen-neuen-lebensabschnitt-erfullend-gestalte\/\">Mehr dazu<\/a><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":551,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,3],"tags":[18],"class_list":["post-566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emotionale-reife","category-selbst-andere","tag-emotionale-reife"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unser Recht auf schlechte Laune |\u00a0The School of Life<\/title>\n<meta name=\"description\" content=\"Die offizielle Religion der Moderne ist das Gl\u00fccklichsein. Das kann auf den ersten Blick gut klingen, aber st\u00e4ndig heiter zu sein, ist eine extrem einschr\u00e4nkende Forderung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.theschooloflife.com\/berlin\/blog\/unser-recht-auf-schlechte-laune\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unser Recht auf schlechte Laune |\u00a0The School of Life\" \/>\n<meta property=\"og:description\" content=\"Die offizielle Religion der Moderne ist das Gl\u00fccklichsein. Das kann auf den ersten Blick gut klingen, aber st\u00e4ndig heiter zu sein, ist eine extrem einschr\u00e4nkende Forderung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.theschooloflife.com\/berlin\/blog\/unser-recht-auf-schlechte-laune\/\" \/>\n<meta property=\"og:site_name\" content=\"Berlin\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-13T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-24T11:39:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2021\/08\/13094745\/Unser-Recht-auf-schlechte-Laune2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"380\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Stefan Gruncharov\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Stefan Gruncharov\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/blog\\\/unser-recht-auf-schlechte-laune\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/blog\\\/unser-recht-auf-schlechte-laune\\\/\"},\"author\":{\"name\":\"Stefan Gruncharov\",\"@id\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/#\\\/schema\\\/person\\\/27ab5838e31e1270c8854d0a6c925dba\"},\"headline\":\"Unser Recht auf schlechte Laune\",\"datePublished\":\"2020-06-13T00:00:00+00:00\",\"dateModified\":\"2024-09-24T11:39:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/blog\\\/unser-recht-auf-schlechte-laune\\\/\"},\"wordCount\":755,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/blog\\\/unser-recht-auf-schlechte-laune\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/assets.theschooloflife.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/08\\\/13094745\\\/Unser-Recht-auf-schlechte-Laune2.jpg.webp\",\"keywords\":[\"emotionale Reife\"],\"articleSection\":[\"emotionale Reife\",\"Selbst &amp; Andere\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/blog\\\/unser-recht-auf-schlechte-laune\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/blog\\\/unser-recht-auf-schlechte-laune\\\/\",\"url\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/blog\\\/unser-recht-auf-schlechte-laune\\\/\",\"name\":\"Unser Recht auf schlechte Laune |\u00a0The School of Life\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/blog\\\/unser-recht-auf-schlechte-laune\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/blog\\\/unser-recht-auf-schlechte-laune\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/assets.theschooloflife.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/08\\\/13094745\\\/Unser-Recht-auf-schlechte-Laune2.jpg.webp\",\"datePublished\":\"2020-06-13T00:00:00+00:00\",\"dateModified\":\"2024-09-24T11:39:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/#\\\/schema\\\/person\\\/27ab5838e31e1270c8854d0a6c925dba\"},\"description\":\"Die offizielle Religion der Moderne ist das Gl\u00fccklichsein. Das kann auf den ersten Blick gut klingen, aber st\u00e4ndig heiter zu sein, ist eine extrem einschr\u00e4nkende Forderung.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/blog\\\/unser-recht-auf-schlechte-laune\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/blog\\\/unser-recht-auf-schlechte-laune\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/blog\\\/unser-recht-auf-schlechte-laune\\\/#primaryimage\",\"url\":\"https:\\\/\\\/assets.theschooloflife.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/08\\\/13094745\\\/Unser-Recht-auf-schlechte-Laune2.jpg.webp\",\"contentUrl\":\"https:\\\/\\\/assets.theschooloflife.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/08\\\/13094745\\\/Unser-Recht-auf-schlechte-Laune2.jpg.webp\",\"width\":1200,\"height\":380},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/blog\\\/unser-recht-auf-schlechte-laune\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unser Recht auf schlechte Laune\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/#website\",\"url\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/\",\"name\":\"Berlin\",\"description\":\"Just another The School Of Life Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/#\\\/schema\\\/person\\\/27ab5838e31e1270c8854d0a6c925dba\",\"name\":\"Stefan Gruncharov\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/429de5e9ec3e912f6f6a1ded8f6fab8bf19f760af5af5e497838c0d441ec60ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/429de5e9ec3e912f6f6a1ded8f6fab8bf19f760af5af5e497838c0d441ec60ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/429de5e9ec3e912f6f6a1ded8f6fab8bf19f760af5af5e497838c0d441ec60ba?s=96&d=mm&r=g\",\"caption\":\"Stefan Gruncharov\"},\"sameAs\":[\"https:\\\/\\\/www.theschooloflife.com\\\/wp\"],\"url\":\"https:\\\/\\\/www.theschooloflife.com\\\/berlin\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unser Recht auf schlechte Laune |\u00a0The School of Life","description":"Die offizielle Religion der Moderne ist das Gl\u00fccklichsein. Das kann auf den ersten Blick gut klingen, aber st\u00e4ndig heiter zu sein, ist eine extrem einschr\u00e4nkende Forderung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.theschooloflife.com\/berlin\/blog\/unser-recht-auf-schlechte-laune\/","og_locale":"de_DE","og_type":"article","og_title":"Unser Recht auf schlechte Laune |\u00a0The School of Life","og_description":"Die offizielle Religion der Moderne ist das Gl\u00fccklichsein. Das kann auf den ersten Blick gut klingen, aber st\u00e4ndig heiter zu sein, ist eine extrem einschr\u00e4nkende Forderung.","og_url":"https:\/\/www.theschooloflife.com\/berlin\/blog\/unser-recht-auf-schlechte-laune\/","og_site_name":"Berlin","article_published_time":"2020-06-13T00:00:00+00:00","article_modified_time":"2024-09-24T11:39:00+00:00","og_image":[{"width":1200,"height":380,"url":"https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2021\/08\/13094745\/Unser-Recht-auf-schlechte-Laune2.jpg","type":"image\/jpeg"}],"author":"Stefan Gruncharov","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Stefan Gruncharov","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.theschooloflife.com\/berlin\/blog\/unser-recht-auf-schlechte-laune\/#article","isPartOf":{"@id":"https:\/\/www.theschooloflife.com\/berlin\/blog\/unser-recht-auf-schlechte-laune\/"},"author":{"name":"Stefan Gruncharov","@id":"https:\/\/www.theschooloflife.com\/berlin\/#\/schema\/person\/27ab5838e31e1270c8854d0a6c925dba"},"headline":"Unser Recht auf schlechte Laune","datePublished":"2020-06-13T00:00:00+00:00","dateModified":"2024-09-24T11:39:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.theschooloflife.com\/berlin\/blog\/unser-recht-auf-schlechte-laune\/"},"wordCount":755,"commentCount":0,"image":{"@id":"https:\/\/www.theschooloflife.com\/berlin\/blog\/unser-recht-auf-schlechte-laune\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2021\/08\/13094745\/Unser-Recht-auf-schlechte-Laune2.jpg.webp","keywords":["emotionale Reife"],"articleSection":["emotionale Reife","Selbst &amp; Andere"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.theschooloflife.com\/berlin\/blog\/unser-recht-auf-schlechte-laune\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.theschooloflife.com\/berlin\/blog\/unser-recht-auf-schlechte-laune\/","url":"https:\/\/www.theschooloflife.com\/berlin\/blog\/unser-recht-auf-schlechte-laune\/","name":"Unser Recht auf schlechte Laune |\u00a0The School of Life","isPartOf":{"@id":"https:\/\/www.theschooloflife.com\/berlin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.theschooloflife.com\/berlin\/blog\/unser-recht-auf-schlechte-laune\/#primaryimage"},"image":{"@id":"https:\/\/www.theschooloflife.com\/berlin\/blog\/unser-recht-auf-schlechte-laune\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2021\/08\/13094745\/Unser-Recht-auf-schlechte-Laune2.jpg.webp","datePublished":"2020-06-13T00:00:00+00:00","dateModified":"2024-09-24T11:39:00+00:00","author":{"@id":"https:\/\/www.theschooloflife.com\/berlin\/#\/schema\/person\/27ab5838e31e1270c8854d0a6c925dba"},"description":"Die offizielle Religion der Moderne ist das Gl\u00fccklichsein. Das kann auf den ersten Blick gut klingen, aber st\u00e4ndig heiter zu sein, ist eine extrem einschr\u00e4nkende Forderung.","breadcrumb":{"@id":"https:\/\/www.theschooloflife.com\/berlin\/blog\/unser-recht-auf-schlechte-laune\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.theschooloflife.com\/berlin\/blog\/unser-recht-auf-schlechte-laune\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.theschooloflife.com\/berlin\/blog\/unser-recht-auf-schlechte-laune\/#primaryimage","url":"https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2021\/08\/13094745\/Unser-Recht-auf-schlechte-Laune2.jpg.webp","contentUrl":"https:\/\/assets.theschooloflife.com\/wp-content\/uploads\/sites\/3\/2021\/08\/13094745\/Unser-Recht-auf-schlechte-Laune2.jpg.webp","width":1200,"height":380},{"@type":"BreadcrumbList","@id":"https:\/\/www.theschooloflife.com\/berlin\/blog\/unser-recht-auf-schlechte-laune\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.theschooloflife.com\/berlin\/"},{"@type":"ListItem","position":2,"name":"Unser Recht auf schlechte Laune"}]},{"@type":"WebSite","@id":"https:\/\/www.theschooloflife.com\/berlin\/#website","url":"https:\/\/www.theschooloflife.com\/berlin\/","name":"Berlin","description":"Just another The School Of Life Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.theschooloflife.com\/berlin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.theschooloflife.com\/berlin\/#\/schema\/person\/27ab5838e31e1270c8854d0a6c925dba","name":"Stefan Gruncharov","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/429de5e9ec3e912f6f6a1ded8f6fab8bf19f760af5af5e497838c0d441ec60ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/429de5e9ec3e912f6f6a1ded8f6fab8bf19f760af5af5e497838c0d441ec60ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/429de5e9ec3e912f6f6a1ded8f6fab8bf19f760af5af5e497838c0d441ec60ba?s=96&d=mm&r=g","caption":"Stefan Gruncharov"},"sameAs":["https:\/\/www.theschooloflife.com\/wp"],"url":"https:\/\/www.theschooloflife.com\/berlin\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.theschooloflife.com\/berlin\/wp-json\/wp\/v2\/posts\/566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.theschooloflife.com\/berlin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.theschooloflife.com\/berlin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.theschooloflife.com\/berlin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.theschooloflife.com\/berlin\/wp-json\/wp\/v2\/comments?post=566"}],"version-history":[{"count":14,"href":"https:\/\/www.theschooloflife.com\/berlin\/wp-json\/wp\/v2\/posts\/566\/revisions"}],"predecessor-version":[{"id":26850,"href":"https:\/\/www.theschooloflife.com\/berlin\/wp-json\/wp\/v2\/posts\/566\/revisions\/26850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.theschooloflife.com\/berlin\/wp-json\/wp\/v2\/media\/551"}],"wp:attachment":[{"href":"https:\/\/www.theschooloflife.com\/berlin\/wp-json\/wp\/v2\/media?parent=566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.theschooloflife.com\/berlin\/wp-json\/wp\/v2\/categories?post=566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.theschooloflife.com\/berlin\/wp-json\/wp\/v2\/tags?post=566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}